{"id":10167,"date":"2025-03-25T11:43:03","date_gmt":"2025-03-25T15:43:03","guid":{"rendered":"https:\/\/www.cadonix.com\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/"},"modified":"2025-04-10T11:58:41","modified_gmt":"2025-04-10T15:58:41","slug":"posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes","status":"publish","type":"faq","link":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/","title":{"rendered":"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sim! Temos um recurso de importa\u00e7\u00e3o f\u00e1cil de usar. Nossa equipe de vendas tamb\u00e9m pode ajudar voc\u00ea com esse processo durante a integra\u00e7\u00e3o.    <\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"faq-category":[400],"class_list":["post-10167","faq","type-faq","status-publish","hentry","faq-category-componentes-conectores-e-pecas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix\" \/>\n<meta property=\"og:description\" content=\"Sim! Temos um recurso de importa\u00e7\u00e3o f\u00e1cil de usar. Nossa equipe de vendas tamb\u00e9m pode ajudar voc\u00ea com esse processo durante a integra\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Cadonix\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T15:58:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/pt-br\\\/faq\\\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\\\/\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/pt-br\\\/faq\\\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\\\/\",\"name\":\"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\"},\"datePublished\":\"2025-03-25T15:43:03+00:00\",\"dateModified\":\"2025-04-10T15:58:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/pt-br\\\/faq\\\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadonix.com\\\/pt-br\\\/faq\\\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/pt-br\\\/faq\\\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadonix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"name\":\"Cadonix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadonix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\",\"name\":\"Cadonix Ltd\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"contentUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"width\":1,\"height\":1,\"caption\":\"Cadonix Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/uk.linkedin.com\\\/company\\\/cadonix\",\"https:\\\/\\\/www.youtube.com\\\/@ArcadiaCAD\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/","og_locale":"pt_BR","og_type":"article","og_title":"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix","og_description":"Sim! Temos um recurso de importa\u00e7\u00e3o f\u00e1cil de usar. Nossa equipe de vendas tamb\u00e9m pode ajudar voc\u00ea com esse processo durante a integra\u00e7\u00e3o.","og_url":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/","og_site_name":"Cadonix","article_modified_time":"2025-04-10T15:58:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/","url":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/","name":"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes? - Cadonix","isPartOf":{"@id":"https:\/\/www.cadonix.com\/#website"},"datePublished":"2025-03-25T15:43:03+00:00","dateModified":"2025-04-10T15:58:41+00:00","breadcrumb":{"@id":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadonix.com\/pt-br\/faq\/posso-importar-minhas-proprias-pecas-para-o-banco-de-dados-de-componentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadonix.com\/"},{"@type":"ListItem","position":2,"name":"Posso importar minhas pr\u00f3prias pe\u00e7as para o banco de dados de componentes?"}]},{"@type":"WebSite","@id":"https:\/\/www.cadonix.com\/#website","url":"https:\/\/www.cadonix.com\/","name":"Cadonix","description":"","publisher":{"@id":"https:\/\/www.cadonix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadonix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.cadonix.com\/#organization","name":"Cadonix Ltd","url":"https:\/\/www.cadonix.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","contentUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","width":1,"height":1,"caption":"Cadonix Ltd"},"image":{"@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/uk.linkedin.com\/company\/cadonix","https:\/\/www.youtube.com\/@ArcadiaCAD"]}]}},"_links":{"self":[{"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/faq\/10167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/types\/faq"}],"version-history":[{"count":0,"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/faq\/10167\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/media?parent=10167"}],"wp:term":[{"taxonomy":"faq-category","embeddable":true,"href":"https:\/\/www.cadonix.com\/pt-br\/wp-json\/wp\/v2\/faq-category?post=10167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}