{"id":713,"date":"2023-03-27T12:40:37","date_gmt":"2023-03-27T16:40:37","guid":{"rendered":"http:\/\/www.cadonix.com:8000\/uncategorized\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/"},"modified":"2025-05-27T13:04:57","modified_gmt":"2025-05-27T17:04:57","slug":"5-caracteristicas-para-probar-durante-su-prueba-gratuita","status":"publish","type":"post","link":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/","title":{"rendered":"5 funciones que debes probar durante la prueba gratuita"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con tu prueba gratuita de Arcadia Design Suite de Cadonix, tienes muchas funciones ricas e intuitivas que explorar. Te recomendamos que experimentes con cinco funciones en particular para hacerte una idea de lo que puedes conseguir con nuestra potente suite de software basada en la nube.   <\/p>\n\n<h2 class=\"wp-block-heading\">1. <strong>Simulaci\u00f3n con ca\u00edda de voltios y se\u00f1al visual <\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Importa un dibujo de tu mazo de cables a Arcadia Schematic desde tu sistema heredado. Puedes averiguar realmente si tu dise\u00f1o funcionar\u00e1 como pretendes. Arcadia Schematic captura informaci\u00f3n sobre tus cables y los circuitos que formar\u00e1n.    <\/p>\n\n<p class=\"wp-block-paragraph\">Puedes simular con precisi\u00f3n tu dise\u00f1o para ver el comportamiento de tu sistema el\u00e9ctrico y c\u00f3mo interact\u00faan entre s\u00ed todos los circuitos. Los gr\u00e1ficos mostrar\u00e1n exactamente lo que ocurre. Si ves, por ejemplo, que una l\u00e1mpara s\u00f3lo consume una peque\u00f1a parte de energ\u00eda, puedes ajustar la resistencia correspondiente hasta que veas que la l\u00e1mpara consume el 100% de energ\u00eda.    <\/p>\n\n<p class=\"wp-block-paragraph\">Con la Base de Datos de Componentes integrada, puedes manejar las propiedades de los cables y calcular realmente las ca\u00eddas de tensi\u00f3n en tiempo real. Tambi\u00e9n puedes asegurarte de que tus circuitos cumplen las normas de seguridad, generar listas de conectividad y especificar los conectores y empalmes a utilizar, incluyendo n\u00fameros de pieza, tablas de cavidades y vistas.   <\/p>\n\n<h2 class=\"wp-block-heading\">2. <strong>Selecciona los cables y conectores esquem\u00e1ticos de la base de datos integrada <\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Crea tu propia lista inteligente de origen a destino. Esto te da una visi\u00f3n completa de todas las conexiones de cables de tu sistema, incluyendo el origen y el destino de cada cable. Tambi\u00e9n puedes utilizar filtros interactivos para ver la informaci\u00f3n de un calibre, color, longitud o ID de cable espec\u00edfico. Genera autom\u00e1ticamente documentaci\u00f3n para tu dise\u00f1o.     <\/p>\n\n<p class=\"wp-block-paragraph\">Puedes utilizar esta informaci\u00f3n para localizar r\u00e1pidamente cables o conexiones concretos, y para identificar las zonas en las que pueden ser necesarios cambios o mejoras. As\u00ed te aseguras de que tu cableado es correcto y eficaz.   <\/p>\n\n<p class=\"wp-block-paragraph\">La Base de Datos de Componentes integrada te permite buscar y elegir f\u00e1cilmente los componentes y conectores adecuados para tus dise\u00f1os de mazos de cables. No s\u00f3lo es una funci\u00f3n incre\u00edblemente c\u00f3moda, sino que te ahorra una gran cantidad de tiempo que de otro modo perder\u00edas buscando las piezas y la informaci\u00f3n adecuadas.   <\/p>\n\n<h2 class=\"wp-block-heading\">3. <strong>Creaci\u00f3n de mazos a partir del esquema <\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Genera la lista de conectividad del arn\u00e9s a partir del Esquema Arcadia con s\u00f3lo pulsar un bot\u00f3n. Tambi\u00e9n te proporciona una sincronizaci\u00f3n bidireccional entre el esquema y el Arn\u00e9s Arcadia con estado de sincronizaci\u00f3n. Esto permite una comunicaci\u00f3n perfecta entre el esquema y el dise\u00f1o del arn\u00e9s, garantizando que cualquier cambio realizado en uno se refleje autom\u00e1ticamente en el otro, y viceversa: no es necesario duplicar esfuerzos.    <\/p>\n\n<p class=\"wp-block-paragraph\">Esta funci\u00f3n garantiza que tu dise\u00f1o se mantenga coherente y actualizado, independientemente de la parte del dise\u00f1o en la que se est\u00e9 trabajando. As\u00ed, si a\u00f1ades un nuevo componente o cambias la ruta de un cable en tu diagrama esquem\u00e1tico, este cambio se actualizar\u00e1 autom\u00e1ticamente en el dise\u00f1o del mazo de cables. Del mismo modo, si a\u00f1ades, por ejemplo, un nuevo conector en el dise\u00f1o del mazo de cables, este cambio se reflejar\u00e1 autom\u00e1ticamente en tu esquema.  <\/p>\n\n<h2 class=\"wp-block-heading\">4. <strong>Selecciona autom\u00e1ticamente terminales, juntas, tapones y cubiertas <\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Nuestra Base de Datos de Componentes dispone de \u201cActualizar Cavidades\u201d. Esto selecciona autom\u00e1ticamente tus terminales, juntas, tapones de cavidades y otros componentes bas\u00e1ndose en los datos de tus cables a partir de los n\u00fameros de pieza del arn\u00e9s y el conector.   <\/p>\n\n<p class=\"wp-block-paragraph\">Esto ayuda a agilizar el proceso de dise\u00f1o y a reducir errores o incoherencias. Esta funci\u00f3n tambi\u00e9n utiliza reglas de dise\u00f1o para comprobar y validar tu dise\u00f1o con la Base de Datos de Componentes. Haz clic en \u201cActualizar tubo manguito\u201d, que obtiene tus recubrimientos bas\u00e1ndose en el di\u00e1metro de tu haz de cables y el valor de referencia seg\u00fan la configuraci\u00f3n de tu perfil.  <\/p>\n\n<p class=\"wp-block-paragraph\">Puedes ver todos los datos de cualquier conector en directo en tu pantalla, eliminando la necesidad de buscar en cat\u00e1logos de papel o en sitios web.<\/p>\n\n<h2 class=\"wp-block-heading\">5. <strong>Generar informes de fabricaci\u00f3n a partir del arn\u00e9s y el tablero de forma completados <\/strong> <\/h2>\n\n<p class=\"wp-block-paragraph\">Puedes generar informes de fabricaci\u00f3n a partir de un arn\u00e9s y un tablero de forma completados, incluida una lista de corte de cables y otros informes relevantes. Genera una lista detallada de todos los componentes y materiales necesarios para fabricar tu arn\u00e9s. Tambi\u00e9n tendr\u00e1s la funcionalidad de generar informes de comprobadores de arneses, como Cirris y Dynalab, para cualquier fallo o defecto, ahorrando un tiempo precioso.    <\/p>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puedes experimentar la sincronizaci\u00f3n entre el arn\u00e9s y el tablero de forma: Esta funci\u00f3n ayuda a una gesti\u00f3n eficaz de los cambios: cualquier cambio realizado en el arn\u00e9s o en el tablero de forma se refleja autom\u00e1ticamente en el otro. Reduce el tiempo y el esfuerzo necesarios para las actualizaciones manuales y garantiza la coherencia del dise\u00f1o. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfTienes alguna duda? Estamos a tu disposici\u00f3n   <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Nuestro paquete de software basado en la nube est\u00e1 dise\u00f1ado para ofrecer una funcionalidad sencilla y f\u00e1cil de usar. Pero si durante tu prueba gratuita ves que algo no te queda claro, preg\u00fantanos: <a href=\"https:\/\/helpdesk.cadonix.online\/\" target=\"_blank\" rel=\"noopener\" title=\"\">siempre estaremos encantados de ayudarte<\/a>. Tambi\u00e9n puedes utilizar nuestra funci\u00f3n de chat en nuestro sitio web cualquier pregunta para obtener las respuestas que necesitas. Por \u00faltimo, puede resultarte \u00fatil <a href=\"https:\/\/pages.cadonix.com\/arcadia-design-suite-bookademo\" target=\"_blank\" rel=\"noopener\" title=\"\">solicitar una demostraci\u00f3n gratuita<\/a> para ayudarte a empezar.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tu prueba gratuita de Arcadia Design Suite de Cadonix, tienes muchas funciones ricas e intuitivas que explorar. Te recomendamos que experimentes con cinco funciones en particular para hacerte una idea de lo que puedes conseguir con nuestra potente suite de software basada en la nube. 1. Simulaci\u00f3n con ca\u00edda de voltios y se\u00f1al visual [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[452],"tags":[],"blog-type":[409],"class_list":["post-713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-como-empezar","blog-type-recursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 funciones que debes probar durante la prueba gratuita - Cadonix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 funciones que debes probar durante la prueba gratuita - Cadonix\" \/>\n<meta property=\"og:description\" content=\"Con tu prueba gratuita de Arcadia Design Suite de Cadonix, tienes muchas funciones ricas e intuitivas que explorar. Te recomendamos que experimentes con cinco funciones en particular para hacerte una idea de lo que puedes conseguir con nuestra potente suite de software basada en la nube. 1. Simulaci\u00f3n con ca\u00edda de voltios y se\u00f1al visual [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/\" \/>\n<meta property=\"og:site_name\" content=\"Cadonix\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T16:40:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-27T17:04:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vipgo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"vipgo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/\"},\"author\":{\"name\":\"vipgo\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/person\\\/0385983b3edcff95387434e1c89a7605\"},\"headline\":\"5 funciones que debes probar durante la prueba gratuita\",\"datePublished\":\"2023-03-27T16:40:37+00:00\",\"dateModified\":\"2025-05-27T17:04:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/\"},\"wordCount\":977,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CadImage2-min.jpg\",\"articleSection\":[\"C\u00f3mo empezar\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/\",\"name\":\"5 funciones que debes probar durante la prueba gratuita - Cadonix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CadImage2-min.jpg\",\"datePublished\":\"2023-03-27T16:40:37+00:00\",\"dateModified\":\"2025-05-27T17:04:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CadImage2-min.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/CadImage2-min.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadonix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 funciones que debes probar durante la prueba gratuita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"name\":\"Cadonix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadonix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\",\"name\":\"Cadonix Ltd\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"contentUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"width\":1,\"height\":1,\"caption\":\"Cadonix Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/uk.linkedin.com\\\/company\\\/cadonix\",\"https:\\\/\\\/www.youtube.com\\\/@ArcadiaCAD\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/person\\\/0385983b3edcff95387434e1c89a7605\",\"name\":\"vipgo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g\",\"caption\":\"vipgo\"},\"url\":\"https:\\\/\\\/www.cadonix.com\\\/es\\\/author\\\/vipgo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 funciones que debes probar durante la prueba gratuita - Cadonix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/","og_locale":"es_ES","og_type":"article","og_title":"5 funciones que debes probar durante la prueba gratuita - Cadonix","og_description":"Con tu prueba gratuita de Arcadia Design Suite de Cadonix, tienes muchas funciones ricas e intuitivas que explorar. Te recomendamos que experimentes con cinco funciones en particular para hacerte una idea de lo que puedes conseguir con nuestra potente suite de software basada en la nube. 1. Simulaci\u00f3n con ca\u00edda de voltios y se\u00f1al visual [&hellip;]","og_url":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/","og_site_name":"Cadonix","article_published_time":"2023-03-27T16:40:37+00:00","article_modified_time":"2025-05-27T17:04:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg","type":"image\/jpeg"}],"author":"vipgo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"vipgo","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#article","isPartOf":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/"},"author":{"name":"vipgo","@id":"https:\/\/www.cadonix.com\/#\/schema\/person\/0385983b3edcff95387434e1c89a7605"},"headline":"5 funciones que debes probar durante la prueba gratuita","datePublished":"2023-03-27T16:40:37+00:00","dateModified":"2025-05-27T17:04:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/"},"wordCount":977,"publisher":{"@id":"https:\/\/www.cadonix.com\/#organization"},"image":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg","articleSection":["C\u00f3mo empezar"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/","url":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/","name":"5 funciones que debes probar durante la prueba gratuita - Cadonix","isPartOf":{"@id":"https:\/\/www.cadonix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#primaryimage"},"image":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg","datePublished":"2023-03-27T16:40:37+00:00","dateModified":"2025-05-27T17:04:57+00:00","breadcrumb":{"@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#primaryimage","url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg","contentUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/01\/CadImage2-min.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadonix.com\/es\/5-caracteristicas-para-probar-durante-su-prueba-gratuita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadonix.com\/"},{"@type":"ListItem","position":2,"name":"5 funciones que debes probar durante la prueba gratuita"}]},{"@type":"WebSite","@id":"https:\/\/www.cadonix.com\/#website","url":"https:\/\/www.cadonix.com\/","name":"Cadonix","description":"","publisher":{"@id":"https:\/\/www.cadonix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadonix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.cadonix.com\/#organization","name":"Cadonix Ltd","url":"https:\/\/www.cadonix.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","contentUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","width":1,"height":1,"caption":"Cadonix Ltd"},"image":{"@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/uk.linkedin.com\/company\/cadonix","https:\/\/www.youtube.com\/@ArcadiaCAD"]},{"@type":"Person","@id":"https:\/\/www.cadonix.com\/#\/schema\/person\/0385983b3edcff95387434e1c89a7605","name":"vipgo","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c000ab86da2e4680de5322d3af5878e26e3c271c3d146116f716f7676681cfe9?s=96&d=mm&r=g","caption":"vipgo"},"url":"https:\/\/www.cadonix.com\/es\/author\/vipgo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/posts\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":0,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/posts\/713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/media\/671"}],"wp:attachment":[{"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/categories?post=713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/tags?post=713"},{"taxonomy":"blog-type","embeddable":true,"href":"https:\/\/www.cadonix.com\/es\/wp-json\/wp\/v2\/blog-type?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}