{"id":16822,"date":"2025-08-15T09:53:16","date_gmt":"2025-08-15T13:53:16","guid":{"rendered":"https:\/\/www.cadonix.com\/besuchen-sie-rebuild-cadonix-auf-der-wiretech-2025\/"},"modified":"2025-10-14T10:24:53","modified_gmt":"2025-10-14T14:24:53","slug":"besuchen-sie-rebuild-cadonix-auf-der-wiretech-2025","status":"publish","type":"post","link":"https:\/\/www.cadonix.com\/de\/besuchen-sie-rebuild-cadonix-auf-der-wiretech-2025\/","title":{"rendered":"Besuchen Sie Re:Build Cadonix auf der WireTech 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16822\" class=\"elementor elementor-16822 elementor-13873\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40ec563 e-flex e-con-boxed cadonix-spacing-none e-con e-parent\" data-id=\"40ec563\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-186d819 elementor-widget elementor-widget-image\" data-id=\"186d819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"267\" src=\"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/WireTech-2025.png\" class=\"attachment-large size-large wp-image-15281\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1e4a19 elementor-widget elementor-widget-spacer\" data-id=\"a1e4a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1200ea elementor-widget elementor-widget-heading\" data-id=\"a1200ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besuchen Sie Cadonix auf der WireTech 2025!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3ee29d elementor-widget elementor-widget-spacer\" data-id=\"f3ee29d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8525d elementor-widget elementor-widget-text-editor\" data-id=\"7f8525d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass <strong>Cadonix auf der <a href=\"https:\/\/elpaso.wiretechmx.com\/\" target=\"_blank\" rel=\"noopener\">WireTech 2025 Konferenz<\/a><\/strong> vom <strong>10. bis 11. September<\/strong> im <strong>El Paso Convention Center in El Paso, TX<\/strong>, <strong>ausstellen wird<\/strong>. Als vertrauensw\u00fcrdiger Name f\u00fcr Cloud-basierte L\u00f6sungen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen sind wir bereit, Ihnen zu zeigen, wie unsere neueste Innovation die Produktion wie nie zuvor rationalisiert. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38da832 elementor-widget elementor-widget-text-editor\" data-id=\"38da832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Besuchen Sie uns an Stand 127<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c96a4a5 elementor-widget elementor-widget-spacer\" data-id=\"c96a4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-871dbb5 elementor-widget elementor-widget-heading\" data-id=\"871dbb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum Sie diese Veranstaltung nicht verpassen sollten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8b534 elementor-widget elementor-widget-text-editor\" data-id=\"5a8b534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die WireTech bringt die besten K\u00f6pfe der Kabelbaumherstellung zusammen und die diesj\u00e4hrige Veranstaltung wird Rekorde brechen. Wir bei Cadonix haben es uns zur Aufgabe gemacht, Herstellern zu helfen, den Wandel zu bew\u00e4ltigen und in einem sich schnell entwickelnden Markt wettbewerbsf\u00e4hig zu bleiben. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80c050c elementor-widget elementor-widget-text-editor\" data-id=\"80c050c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>An unserem Stand haben Sie die M\u00f6glichkeit,:<\/p><ul class=\"wp-block-list\"><li><p>In <strong>einem pers\u00f6nlichen Gespr\u00e4ch<\/strong> mit unseren Ingenieuren und Produktspezialisten erfahren Sie, wie die<a href=\"https:\/\/www.cadonix.com\/de\/ressourcen\/?_blog_post_categories=release-notes\" target=\"_blank\" rel=\"noopener\"> neuesten Arcadia-Funktionen<\/a> den Design- und Herstellungsprozess von Kabelb\u00e4umen optimieren.<\/p><\/li><li><p><strong>Entdecken Sie, wie <a href=\"https:\/\/www.cadonix.com\/de\/warum-arkadien\/\" target=\"_blank\" rel=\"noopener\">Arcadia<\/a> Ihnen hilft, Kosten zu senken<\/strong> und die Markteinf\u00fchrung zu beschleunigen, indem es ein schnelleres Design, eine nahtlose Zusammenarbeit im Team und eine genauere Berichterstattung erm\u00f6glicht.<\/p><\/li><li><p><strong>Erhalten Sie einen exklusiven Vorgeschmack<\/strong> auf das, was als N\u00e4chstes in unserer sich weiterentwickelnden Plattform kommt, um sie zu einer noch leistungsf\u00e4higeren Produktionsplattform zu machen.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Besuchen Sie Cadonix auf der WireTech 2025! Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass Cadonix auf der WireTech 2025 Konferenz vom 10. bis 11. September im El Paso Convention Center in El Paso, TX, ausstellen wird. Als vertrauensw\u00fcrdiger Name f\u00fcr Cloud-basierte L\u00f6sungen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen sind wir bereit, Ihnen [&hellip;]<\/p>\n","protected":false},"author":5005,"featured_media":15307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[549],"tags":[],"blog-type":[422,421],"class_list":["post-16822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ereignisse","blog-type-nachrichten","blog-type-ressource"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix<\/title>\n<meta name=\"description\" content=\"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cadonix.com\/de\/?p=16822\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix\" \/>\n<meta property=\"og:description\" content=\"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cadonix.com\/de\/?p=16822\" \/>\n<meta property=\"og:site_name\" content=\"Cadonix\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T13:53:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T14:24:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Florida Web &amp; Marketing Solutions\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Florida Web &amp; Marketing Solutions\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822\"},\"author\":{\"name\":\"Florida Web &amp; Marketing Solutions\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/person\\\/afcb798d65b0b6c050f5a69615d79e5d\"},\"headline\":\"Besuchen Sie Re:Build Cadonix auf der WireTech 2025\",\"datePublished\":\"2025-08-15T13:53:16+00:00\",\"dateModified\":\"2025-10-14T14:24:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ReBuild-Cadonix-WireTech-2025.png\",\"articleSection\":[\"Ereignisse\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822\",\"name\":\"WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ReBuild-Cadonix-WireTech-2025.png\",\"datePublished\":\"2025-08-15T13:53:16+00:00\",\"dateModified\":\"2025-10-14T14:24:53+00:00\",\"description\":\"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#primaryimage\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ReBuild-Cadonix-WireTech-2025.png\",\"contentUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/ReBuild-Cadonix-WireTech-2025.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/?p=16822#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cadonix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Besuchen Sie Re:Build Cadonix auf der WireTech 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"name\":\"Cadonix\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cadonix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#organization\",\"name\":\"Cadonix Ltd\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"contentUrl\":\"https:\\\/\\\/www.cadonix.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/0-Company-OurBusinesses-Cadonix2.svg.svg\",\"width\":1,\"height\":1,\"caption\":\"Cadonix Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/uk.linkedin.com\\\/company\\\/cadonix\",\"https:\\\/\\\/www.youtube.com\\\/@ArcadiaCAD\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cadonix.com\\\/#\\\/schema\\\/person\\\/afcb798d65b0b6c050f5a69615d79e5d\",\"name\":\"Florida Web &amp; Marketing Solutions\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g\",\"caption\":\"Florida Web &amp; Marketing Solutions\"},\"sameAs\":[\"https:\\\/\\\/www.floridawebandmarketing.com\"],\"url\":\"https:\\\/\\\/www.cadonix.com\\\/de\\\/author\\\/maryb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix","description":"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cadonix.com\/de\/?p=16822","og_locale":"de_DE","og_type":"article","og_title":"WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix","og_description":"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.","og_url":"https:\/\/www.cadonix.com\/de\/?p=16822","og_site_name":"Cadonix","article_published_time":"2025-08-15T13:53:16+00:00","article_modified_time":"2025-10-14T14:24:53+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png","type":"image\/png"}],"author":"Florida Web &amp; Marketing Solutions","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Florida Web &amp; Marketing Solutions","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cadonix.com\/de\/?p=16822#article","isPartOf":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822"},"author":{"name":"Florida Web &amp; Marketing Solutions","@id":"https:\/\/www.cadonix.com\/#\/schema\/person\/afcb798d65b0b6c050f5a69615d79e5d"},"headline":"Besuchen Sie Re:Build Cadonix auf der WireTech 2025","datePublished":"2025-08-15T13:53:16+00:00","dateModified":"2025-10-14T14:24:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/www.cadonix.com\/#organization"},"image":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822#primaryimage"},"thumbnailUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png","articleSection":["Ereignisse"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cadonix.com\/de\/?p=16822#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cadonix.com\/de\/?p=16822","url":"https:\/\/www.cadonix.com\/de\/?p=16822","name":"WireTech 2025: Besuchen Sie Re:Build Cadonix an Stand 127 - Cadonix","isPartOf":{"@id":"https:\/\/www.cadonix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822#primaryimage"},"image":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822#primaryimage"},"thumbnailUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png","datePublished":"2025-08-15T13:53:16+00:00","dateModified":"2025-10-14T14:24:53+00:00","description":"Begleiten Sie Re:Build Cadonix auf der WireTech 2025, wenn wir die neuesten Arcadia-Funktionen f\u00fcr das Design und die Herstellung von Kabelb\u00e4umen vorstellen.","breadcrumb":{"@id":"https:\/\/www.cadonix.com\/de\/?p=16822#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cadonix.com\/de\/?p=16822"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.cadonix.com\/de\/?p=16822#primaryimage","url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png","contentUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/08\/ReBuild-Cadonix-WireTech-2025.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.cadonix.com\/de\/?p=16822#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cadonix.com\/"},{"@type":"ListItem","position":2,"name":"Besuchen Sie Re:Build Cadonix auf der WireTech 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.cadonix.com\/#website","url":"https:\/\/www.cadonix.com\/","name":"Cadonix","description":"","publisher":{"@id":"https:\/\/www.cadonix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cadonix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.cadonix.com\/#organization","name":"Cadonix Ltd","url":"https:\/\/www.cadonix.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","contentUrl":"https:\/\/www.cadonix.com\/wp-content\/uploads\/2025\/03\/0-Company-OurBusinesses-Cadonix2.svg.svg","width":1,"height":1,"caption":"Cadonix Ltd"},"image":{"@id":"https:\/\/www.cadonix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/uk.linkedin.com\/company\/cadonix","https:\/\/www.youtube.com\/@ArcadiaCAD"]},{"@type":"Person","@id":"https:\/\/www.cadonix.com\/#\/schema\/person\/afcb798d65b0b6c050f5a69615d79e5d","name":"Florida Web &amp; Marketing Solutions","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb8421e6d113798fb841ea2a9624f020d5cbd88533447d3c67e3e89b1ac74b4d?s=96&d=mm&r=g","caption":"Florida Web &amp; Marketing Solutions"},"sameAs":["https:\/\/www.floridawebandmarketing.com"],"url":"https:\/\/www.cadonix.com\/de\/author\/maryb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/posts\/16822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/users\/5005"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/comments?post=16822"}],"version-history":[{"count":0,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/posts\/16822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/media\/15307"}],"wp:attachment":[{"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/media?parent=16822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/categories?post=16822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/tags?post=16822"},{"taxonomy":"blog-type","embeddable":true,"href":"https:\/\/www.cadonix.com\/de\/wp-json\/wp\/v2\/blog-type?post=16822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}